{"id":15059,"date":"2013-09-26T21:42:06","date_gmt":"2013-09-26T19:42:06","guid":{"rendered":"http:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene.jpg"},"modified":"2013-09-26T21:42:06","modified_gmt":"2013-09-26T19:42:06","slug":"ida-og-rosene","status":"inherit","type":"attachment","link":"https:\/\/grete.duna.no\/blog\/2013\/09\/26\/aktive-dager\/ida-og-rosene\/","title":{"rendered":"ida-og-rosene"},"author":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene.jpg'><img width=\"225\" height=\"300\" src=\"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene-225x300.jpg 225w, https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene.jpg 600w\" sizes=\"(max-width: 225px) 85vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":800,"file":"2013\/09\/ida-og-rosene.jpg","sizes":{"thumbnail":{"file":"ida-og-rosene-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene-180x180.jpg"},"medium":{"file":"ida-og-rosene-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene-225x300.jpg"},"full":{"file":"ida-og-rosene.jpg","width":600,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene.jpg"}},"image_meta":{"aperture":3.3,"credit":"","camera":"DMC-TZ30","caption":"","created_timestamp":1380214026,"copyright":"","focal_length":"4.3","iso":"320","shutter_speed":"0.004","title":""}},"post":15055,"source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2013\/09\/ida-og-rosene.jpg","_links":{"self":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/media\/15059"}],"collection":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/comments?post=15059"}]}}