{"id":18555,"date":"2015-01-22T20:29:58","date_gmt":"2015-01-22T19:29:58","guid":{"rendered":"http:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu.jpg"},"modified":"2015-01-22T20:29:58","modified_gmt":"2015-01-22T19:29:58","slug":"nodekart-med-gretebu","status":"inherit","type":"attachment","link":"https:\/\/grete.duna.no\/blog\/2015\/01\/22\/rapport-by-proxy-2\/nodekart-med-gretebu\/","title":{"rendered":"nodekart-med-gretebu"},"author":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu.jpg'><img width=\"300\" height=\"157\" src=\"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-300x157.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-300x157.jpg 300w, https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-1024x537.jpg 1024w, https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu.jpg 1280w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":671,"file":"2015\/01\/nodekart-med-gretebu.jpg","sizes":{"thumbnail":{"file":"nodekart-med-gretebu-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-180x180.jpg"},"medium":{"file":"nodekart-med-gretebu-300x157.jpg","width":300,"height":157,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-300x157.jpg"},"large":{"file":"nodekart-med-gretebu-1024x537.jpg","width":1024,"height":537,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-1024x537.jpg"},"post-thumbnail":{"file":"nodekart-med-gretebu-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-672x372.jpg"},"twentyfourteen-full-width":{"file":"nodekart-med-gretebu-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-1038x576.jpg"},"album-thumb":{"file":"nodekart-med-gretebu-140x105.jpg","width":140,"height":105,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-140x105.jpg"},"photo-thumb":{"file":"nodekart-med-gretebu-140x105.jpg","width":140,"height":105,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu-140x105.jpg"},"full":{"file":"nodekart-med-gretebu.jpg","width":1280,"height":671,"mime_type":"image\/jpeg","source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":1}},"post":18553,"source_url":"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2015\/01\/nodekart-med-gretebu.jpg","_links":{"self":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/media\/18555"}],"collection":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/comments?post=18555"}]}}