{"id":8441,"date":"2011-08-04T00:19:35","date_gmt":"2011-08-03T22:19:35","guid":{"rendered":"http:\/\/grete.duna.no\/blog\/?p=8441"},"modified":"2011-08-03T22:21:06","modified_gmt":"2011-08-03T20:21:06","slug":"observatorene","status":"publish","type":"post","link":"https:\/\/grete.duna.no\/blog\/2011\/08\/04\/observatorene\/","title":{"rendered":"Observat\u00f8rene"},"content":{"rendered":"<p>Lukas er s\u00e5 snedig &#8211; hvis noen ser ut til \u00e5 lete etter noe, eller kikke p\u00e5 noe, s\u00e5 gj\u00f8r han det samme. Her er han fanget i et \u00f8yeblikk p\u00e5 kaia. Tobias kikker over kanten, Lukas likes\u00e5. Mon tro om de s\u00e5 noe spennende?<\/p>\n<figure id=\"attachment_8442\" aria-describedby=\"caption-attachment-8442\" style=\"width: 540px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2011\/08\/lukas-og-tobias-ser-noe.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-8442 \" style=\"border: 1px solid black; margin-top: 1px; margin-bottom: 1px;\" title=\"lukas-og-tobias-ser-noe\" src=\"http:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2011\/08\/lukas-og-tobias-ser-noe.jpg\" alt=\"\" width=\"540\" height=\"396\" srcset=\"https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2011\/08\/lukas-og-tobias-ser-noe.jpg 600w, https:\/\/grete.duna.no\/blog\/wp-content\/uploads\/2011\/08\/lukas-og-tobias-ser-noe-300x220.jpg 300w\" sizes=\"(max-width: 540px) 85vw, 540px\" \/><\/a><figcaption id=\"caption-attachment-8442\" class=\"wp-caption-text\">Er det noe \u00e5 se der nede, tro?<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lukas er s\u00e5 snedig &#8211; hvis noen ser ut til \u00e5 lete etter noe, eller kikke p\u00e5 noe, s\u00e5 gj\u00f8r han det samme. Her er han fanget i et \u00f8yeblikk p\u00e5 kaia. Tobias kikker over kanten, Lukas likes\u00e5. Mon tro om de s\u00e5 noe spennende?<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9,11,39,6],"tags":[53,46,76,22],"_links":{"self":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/posts\/8441"}],"collection":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/comments?post=8441"}],"version-history":[{"count":4,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/posts\/8441\/revisions"}],"predecessor-version":[{"id":8446,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/posts\/8441\/revisions\/8446"}],"wp:attachment":[{"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/media?parent=8441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/categories?post=8441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grete.duna.no\/blog\/wp-json\/wp\/v2\/tags?post=8441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}